{"id":10665,"date":"2018-07-13T11:49:39","date_gmt":"2018-07-13T11:49:39","guid":{"rendered":"https:\/\/proagrolab.com.ar\/?p=10665"},"modified":"2018-07-13T14:29:45","modified_gmt":"2018-07-13T14:29:45","slug":"se-viene-una-nueva-edicion-de-la-escuela-de-jurados-de-la-raza-angus","status":"publish","type":"post","link":"https:\/\/proagrolab.com.ar\/en\/se-viene-una-nueva-edicion-de-la-escuela-de-jurados-de-la-raza-angus\/","title":{"rendered":"Se viene una nueva edici\u00f3n de la Escuela de Jurados de la raza Angus"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\"> <\/p><p><\/p>\n<h2>Es una muy buena oportunidad para quienes quieren capacitarse en las caracter\u00edsticas de este rodeo, con clases te\u00f3ricas y en las caba\u00f1as.<\/h2>\n<p><a href=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/07\/S1GyfzyMM_930x525.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-10666 size-full\" src=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/07\/S1GyfzyMM_930x525.jpg\" alt=\"\" width=\"930\" height=\"525\" srcset=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/07\/S1GyfzyMM_930x525.jpg 930w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/07\/S1GyfzyMM_930x525-600x339.jpg 600w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/07\/S1GyfzyMM_930x525-300x169.jpg 300w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/07\/S1GyfzyMM_930x525-768x434.jpg 768w\" sizes=\"auto, (max-width: 930px) 100vw, 930px\" \/><\/a><\/p>\n<p>Del 16 al 20 de julio, se realizar\u00e1 en Buenos Aires una nueva edici\u00f3n de la Escuela de Jurados y bases productivas de la raza Angus, que organiza la Asociaci\u00f3n Argentina de Angus.<\/p>\n<p>&#8220;El objetivo de esta\u00a0capacitaci\u00f3n intensiva es formar a estudiantes, profesionales e interesados en general, en conocimientos espec\u00edficos sobre la raza, que puedan ser aplicados tanto en la jura de ejemplares en las pistas, como en la selecci\u00f3n de animales para caba\u00f1as y rodeos productivos&#8221;, explicaron desde la asociaci\u00f3n.<\/p>\n<p>El curso, dictado por prestigiosos especialistas, se compone de clases te\u00f3ricas sobre caracter\u00edsticas anat\u00f3micas y fisiol\u00f3gicas de los bovinos, criterios para seleccionar el ganado, toma de datos, evaluaci\u00f3n gen\u00e9tica y particularidades del negocio.<\/p>\n<div class=\"widget content-new\">\n<div class=\"mg\">\n<div class=\"wrap-figure\">\n<p>Los alumnos tendr\u00e1n la posibilidad de realizar clases pr\u00e1cticas en caba\u00f1as Angus y en la pista central de La Rural de Palermo, para validar los conocimientos te\u00f3ricos.<\/p>\n<p>Adem\u00e1s, se concretar\u00e1 una visita al Mercado de Liniers para presenciar un remate de la firma Alzaga Unzu\u00e9 y conocer los criterios de clasificaci\u00f3n de novillos, as\u00ed como el sistema de trazabilidad del mercado.<\/p>\n<p>Estar\u00e1n a cargo de las clases Sebasti\u00e1n Rodr\u00edguez Larreta, Ignacio Harris, Marcelo Tropeano, Alfonso Bustillo, Horacio Guitou, Carlos Ojea Rull\u00e1n, Mauricio Groppo y Carlos Pestalardo Guerrero, entre otros.<\/p>\n<p>Los interesados pueden solicitar m\u00e1s informaci\u00f3n a los mails:\u00a0remates@angus.org.ar y admin@angus.org.ar; o a el tel\u00e9fono\u00a0011-4774-0065.<\/p>\n<p>Fuente:\u00a0https:\/\/www.clarin.com\/rural\/viene-nueva-edicion-escuela-jurados-raza-angus_0_Hk_CH72fX.html<\/p>\n<\/div>\n<\/div>\n<\/div>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Es una muy buena oportunidad para quienes quieren capacitarse en las caracter\u00edsticas de este rodeo, con clases te\u00f3ricas y en las caba\u00f1as. Del 16 al 20 de julio, se realizar\u00e1 en Buenos Aires una nueva edici\u00f3n de la Escuela de Jurados y bases productivas de la raza Angus, que organiza la Asociaci\u00f3n Argentina de Angus. &#8220;El objetivo de esta\u00a0capacitaci\u00f3n intensiva es formar a estudiantes, profesionales e interesados en general, en conocimientos espec\u00edficos sobre la raza, que puedan ser aplicados tanto en la jura de ejemplares en las pistas, como en la selecci\u00f3n de animales para caba\u00f1as y rodeos productivos&#8221;, explicaron desde la asociaci\u00f3n. El curso, dictado por prestigiosos especialistas, se compone de clases te\u00f3ricas sobre caracter\u00edsticas anat\u00f3micas y fisiol\u00f3gicas de los bovinos, criterios para seleccionar el ganado, toma de datos, evaluaci\u00f3n gen\u00e9tica y particularidades del negocio. Los alumnos tendr\u00e1n la posibilidad de realizar clases pr\u00e1cticas en caba\u00f1as Angus y en la pista central de La Rural de Palermo, para validar los conocimientos te\u00f3ricos. Adem\u00e1s, se concretar\u00e1 una visita al Mercado de Liniers para presenciar un remate de la firma Alzaga Unzu\u00e9 y conocer los criterios de clasificaci\u00f3n de novillos, as\u00ed como el sistema de trazabilidad del mercado. Estar\u00e1n a cargo [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":10676,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[56],"tags":[],"class_list":["post-10665","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infoganadero"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Se viene una nueva edici\u00f3n de la Escuela de Jurados de la raza Angus | Proagro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proagrolab.com.ar\/en\/se-viene-una-nueva-edicion-de-la-escuela-de-jurados-de-la-raza-angus\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Se viene una nueva edici\u00f3n de la Escuela de Jurados de la raza Angus | Proagro\" \/>\n<meta property=\"og:description\" content=\"Es una muy buena oportunidad para quienes quieren capacitarse en las caracter\u00edsticas de este rodeo, con clases te\u00f3ricas y en las caba\u00f1as. Del 16 al 20 de julio, se realizar\u00e1 en Buenos Aires una nueva edici\u00f3n de la Escuela de Jurados y bases productivas de la raza Angus, que organiza la Asociaci\u00f3n Argentina de Angus. &#8220;El objetivo de esta\u00a0capacitaci\u00f3n intensiva es formar a estudiantes, profesionales e interesados en general, en conocimientos espec\u00edficos sobre la raza, que puedan ser aplicados tanto en la jura de ejemplares en las pistas, como en la selecci\u00f3n de animales para caba\u00f1as y rodeos productivos&#8221;, explicaron desde la asociaci\u00f3n. El curso, dictado por prestigiosos especialistas, se compone de clases te\u00f3ricas sobre caracter\u00edsticas anat\u00f3micas y fisiol\u00f3gicas de los bovinos, criterios para seleccionar el ganado, toma de datos, evaluaci\u00f3n gen\u00e9tica y particularidades del negocio. Los alumnos tendr\u00e1n la posibilidad de realizar clases pr\u00e1cticas en caba\u00f1as Angus y en la pista central de La Rural de Palermo, para validar los conocimientos te\u00f3ricos. Adem\u00e1s, se concretar\u00e1 una visita al Mercado de Liniers para presenciar un remate de la firma Alzaga Unzu\u00e9 y conocer los criterios de clasificaci\u00f3n de novillos, as\u00ed como el sistema de trazabilidad del mercado. Estar\u00e1n a cargo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proagrolab.com.ar\/se-viene-una-nueva-edicion-de-la-escuela-de-jurados-de-la-raza-angus\/\" \/>\n<meta property=\"og:site_name\" content=\"Proagro\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/proagrolab\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-13T11:49:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-07-13T14:29:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/07\/1145x395-13072018.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1145\" \/>\n\t<meta property=\"og:image:height\" content=\"395\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin Proagro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin Proagro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/se-viene-una-nueva-edicion-de-la-escuela-de-jurados-de-la-raza-angus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/se-viene-una-nueva-edicion-de-la-escuela-de-jurados-de-la-raza-angus\\\/\"},\"author\":{\"name\":\"Admin Proagro\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/3e30f2f0f9eadcc02d50ed3664562373\"},\"headline\":\"Se viene una nueva edici\u00f3n de la Escuela de Jurados de la raza Angus\",\"datePublished\":\"2018-07-13T11:49:39+00:00\",\"dateModified\":\"2018-07-13T14:29:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/se-viene-una-nueva-edicion-de-la-escuela-de-jurados-de-la-raza-angus\\\/\"},\"wordCount\":305,\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/se-viene-una-nueva-edicion-de-la-escuela-de-jurados-de-la-raza-angus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/1145x395-13072018.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/se-viene-una-nueva-edicion-de-la-escuela-de-jurados-de-la-raza-angus\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/se-viene-una-nueva-edicion-de-la-escuela-de-jurados-de-la-raza-angus\\\/\",\"name\":\"Se viene una nueva edici\u00f3n de la Escuela de Jurados de la raza Angus | Proagro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/se-viene-una-nueva-edicion-de-la-escuela-de-jurados-de-la-raza-angus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/se-viene-una-nueva-edicion-de-la-escuela-de-jurados-de-la-raza-angus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/1145x395-13072018.jpg\",\"datePublished\":\"2018-07-13T11:49:39+00:00\",\"dateModified\":\"2018-07-13T14:29:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/se-viene-una-nueva-edicion-de-la-escuela-de-jurados-de-la-raza-angus\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proagrolab.com.ar\\\/se-viene-una-nueva-edicion-de-la-escuela-de-jurados-de-la-raza-angus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/se-viene-una-nueva-edicion-de-la-escuela-de-jurados-de-la-raza-angus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/1145x395-13072018.jpg\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/1145x395-13072018.jpg\",\"width\":1145,\"height\":395},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/se-viene-una-nueva-edicion-de-la-escuela-de-jurados-de-la-raza-angus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/proagrolab.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se viene una nueva edici\u00f3n de la Escuela de Jurados de la raza Angus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"name\":\"Proagro Laboratorio Veterinario\",\"description\":\"Veterinary laboratory\",\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proagrolab.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\",\"name\":\"Proagro\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"width\":478,\"height\":120,\"caption\":\"Proagro\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/proagrolab\",\"https:\\\/\\\/www.instagram.com\\\/proagrolab\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/laboratorio-proagro-s-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/3e30f2f0f9eadcc02d50ed3664562373\",\"name\":\"Admin Proagro\",\"sameAs\":[\"http:\\\/\\\/www.sistemas7g.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Se viene una nueva edici\u00f3n de la Escuela de Jurados de la raza Angus | Proagro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proagrolab.com.ar\/en\/se-viene-una-nueva-edicion-de-la-escuela-de-jurados-de-la-raza-angus\/","og_locale":"en_US","og_type":"article","og_title":"Se viene una nueva edici\u00f3n de la Escuela de Jurados de la raza Angus | Proagro","og_description":"Es una muy buena oportunidad para quienes quieren capacitarse en las caracter\u00edsticas de este rodeo, con clases te\u00f3ricas y en las caba\u00f1as. Del 16 al 20 de julio, se realizar\u00e1 en Buenos Aires una nueva edici\u00f3n de la Escuela de Jurados y bases productivas de la raza Angus, que organiza la Asociaci\u00f3n Argentina de Angus. &#8220;El objetivo de esta\u00a0capacitaci\u00f3n intensiva es formar a estudiantes, profesionales e interesados en general, en conocimientos espec\u00edficos sobre la raza, que puedan ser aplicados tanto en la jura de ejemplares en las pistas, como en la selecci\u00f3n de animales para caba\u00f1as y rodeos productivos&#8221;, explicaron desde la asociaci\u00f3n. El curso, dictado por prestigiosos especialistas, se compone de clases te\u00f3ricas sobre caracter\u00edsticas anat\u00f3micas y fisiol\u00f3gicas de los bovinos, criterios para seleccionar el ganado, toma de datos, evaluaci\u00f3n gen\u00e9tica y particularidades del negocio. Los alumnos tendr\u00e1n la posibilidad de realizar clases pr\u00e1cticas en caba\u00f1as Angus y en la pista central de La Rural de Palermo, para validar los conocimientos te\u00f3ricos. Adem\u00e1s, se concretar\u00e1 una visita al Mercado de Liniers para presenciar un remate de la firma Alzaga Unzu\u00e9 y conocer los criterios de clasificaci\u00f3n de novillos, as\u00ed como el sistema de trazabilidad del mercado. Estar\u00e1n a cargo [&hellip;]","og_url":"https:\/\/proagrolab.com.ar\/se-viene-una-nueva-edicion-de-la-escuela-de-jurados-de-la-raza-angus\/","og_site_name":"Proagro","article_publisher":"http:\/\/www.facebook.com\/proagrolab","article_published_time":"2018-07-13T11:49:39+00:00","article_modified_time":"2018-07-13T14:29:45+00:00","og_image":[{"width":1145,"height":395,"url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/07\/1145x395-13072018.jpg","type":"image\/jpeg"}],"author":"Admin Proagro","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Admin Proagro","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proagrolab.com.ar\/se-viene-una-nueva-edicion-de-la-escuela-de-jurados-de-la-raza-angus\/#article","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/se-viene-una-nueva-edicion-de-la-escuela-de-jurados-de-la-raza-angus\/"},"author":{"name":"Admin Proagro","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/3e30f2f0f9eadcc02d50ed3664562373"},"headline":"Se viene una nueva edici\u00f3n de la Escuela de Jurados de la raza Angus","datePublished":"2018-07-13T11:49:39+00:00","dateModified":"2018-07-13T14:29:45+00:00","mainEntityOfPage":{"@id":"https:\/\/proagrolab.com.ar\/se-viene-una-nueva-edicion-de-la-escuela-de-jurados-de-la-raza-angus\/"},"wordCount":305,"publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"image":{"@id":"https:\/\/proagrolab.com.ar\/se-viene-una-nueva-edicion-de-la-escuela-de-jurados-de-la-raza-angus\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/07\/1145x395-13072018.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/proagrolab.com.ar\/se-viene-una-nueva-edicion-de-la-escuela-de-jurados-de-la-raza-angus\/","url":"https:\/\/proagrolab.com.ar\/se-viene-una-nueva-edicion-de-la-escuela-de-jurados-de-la-raza-angus\/","name":"Se viene una nueva edici\u00f3n de la Escuela de Jurados de la raza Angus | Proagro","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proagrolab.com.ar\/se-viene-una-nueva-edicion-de-la-escuela-de-jurados-de-la-raza-angus\/#primaryimage"},"image":{"@id":"https:\/\/proagrolab.com.ar\/se-viene-una-nueva-edicion-de-la-escuela-de-jurados-de-la-raza-angus\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/07\/1145x395-13072018.jpg","datePublished":"2018-07-13T11:49:39+00:00","dateModified":"2018-07-13T14:29:45+00:00","breadcrumb":{"@id":"https:\/\/proagrolab.com.ar\/se-viene-una-nueva-edicion-de-la-escuela-de-jurados-de-la-raza-angus\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proagrolab.com.ar\/se-viene-una-nueva-edicion-de-la-escuela-de-jurados-de-la-raza-angus\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/se-viene-una-nueva-edicion-de-la-escuela-de-jurados-de-la-raza-angus\/#primaryimage","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/07\/1145x395-13072018.jpg","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/07\/1145x395-13072018.jpg","width":1145,"height":395},{"@type":"BreadcrumbList","@id":"https:\/\/proagrolab.com.ar\/se-viene-una-nueva-edicion-de-la-escuela-de-jurados-de-la-raza-angus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proagrolab.com.ar\/"},{"@type":"ListItem","position":2,"name":"Se viene una nueva edici\u00f3n de la Escuela de Jurados de la raza Angus"}]},{"@type":"WebSite","@id":"https:\/\/proagrolab.com.ar\/#website","url":"https:\/\/proagrolab.com.ar\/","name":"Proagro Laboratorio Veterinario","description":"Veterinary laboratory","publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proagrolab.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/proagrolab.com.ar\/#organization","name":"Proagro","url":"https:\/\/proagrolab.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","width":478,"height":120,"caption":"Proagro"},"image":{"@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/proagrolab","https:\/\/www.instagram.com\/proagrolab\/","https:\/\/www.linkedin.com\/company\/laboratorio-proagro-s-a\/"]},{"@type":"Person","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/3e30f2f0f9eadcc02d50ed3664562373","name":"Admin Proagro","sameAs":["http:\/\/www.sistemas7g.com"]}]}},"_links":{"self":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/10665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/comments?post=10665"}],"version-history":[{"count":0,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/10665\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media\/10676"}],"wp:attachment":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media?parent=10665"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/categories?post=10665"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/tags?post=10665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}